{"id":705,"date":"2017-02-17T10:45:37","date_gmt":"2017-02-17T10:45:37","guid":{"rendered":"http:\/\/www.julianpiscinas.com\/?page_id=705"},"modified":"2023-07-19T11:35:42","modified_gmt":"2023-07-19T11:35:42","slug":"construccion-de-piscinas-en-tarragona","status":"publish","type":"page","link":"http:\/\/www.julianpiscinas.com\/ca\/construccion-de-piscinas-en-tarragona\/","title":{"rendered":"Construcci\u00f3 de piscines a Tarragona"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2020\/03\/pool-construction.jpg\u00bb custom_padding=\u00bb0px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb7%||7%||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|||on|||||\u00bb text_text_color=\u00bb#ffffffd0&#8243; header_font=\u00bb|||on|||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#ffffff\u00bb header_font_size=\u00bb36px\u00bb background_color=\u00bbrgba(0,0,0,0.62)\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb width=\u00bb98%\u00bb max_width=\u00bb900px\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb1em|1em|1em|1em|true|true\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|desktop\u00bb header_font_size_tablet=\u00bb30px\u00bb header_font_size_phone=\u00bb24px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb text_text_shadow_style=\u00bbpreset5&#8243; text_text_shadow_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>Construcci\u00f3n de piscinas en Tarragona<\/strong><\/h1>\n<h2>Piscinas de obra de todos los tama\u00f1os<\/h2>\n<p class=\"first-p\">Empresa constructora experta en <strong>construcci\u00f3n de piscinas en la provincia Tarragona<\/strong> | Piscinas de gunitado | Piscinas de liner armado de PVC<\/p>\n<p>Construimos tu piscina al mejor precio en cualquier tama\u00f1o<br \/>Julian Pisicinas Tarragona<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIxMSJ9fQ==@\u00bb button_text=\u00bbSolicita informaci\u00f3n\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.17.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#006AC1&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb2px\u00bb button_use_icon=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbtel:+34600811678&#8243; button_text=\u00bbPulsa para llamar\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#7CDA24&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb2px\u00bb button_icon=\u00bb&#xe090;||divi||400&#8243; button_icon_color=\u00bb#000000&#8243; button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; admin_label=\u00bbFila\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/02\/piscinas-mini.jpg\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text admin_label=\u00bbTexto\u00bb _builder_version=\u00bb4.17.4&#8243; header_3_font=\u00bb|600|||||||\u00bb header_3_text_align=\u00bbcenter\u00bb header_4_text_color=\u00bb#e09900&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; text_font_size=\u00bb15px\u00bb]<\/p>\n<p><span style=\"display: block; font-size: 2.3em; line-height: 1.2em; text-align: left; text-shadow: 4px 2px 2px #006ac1;\">\u00a1Los dise\u00f1adores y constructores de Juli\u00e1n Piscinas llevamos tu piscina desde el estado de proyecto a la realidad!<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Empresa de construcci\u00f3n de piscinas en Tarragona<\/strong><span style=\"display: block; font-size: 2em; line-height: 1.5em;\"><\/span><\/h2>\n<p>Realizamos <strong>construcciones de piscinas en <a href=\"https:\/\/www.google.com\/maps\/place\/Tarragona\/@41.0514691,0.3457535,9z\/data=!4m5!3m4!1s0x12a1475f666439ed:0x300fae021a3cbe0!8m2!3d41.1188343!4d1.2444774\">Tarragona<\/a>.<\/strong> Contamos con d\u00e9cadas de experiencia en el sector de las piscinas y hemos ejecutado cientos de instalaciones de piscinas en la provincia Tarragona (Tarragona, Reus, Torredembarra, Cambrils, Salou etc.) y cercan\u00edas.<\/p>\n<p>A lo largo de nuestra trayectoria profesional siempre nos hemos adaptado a las nuevas tendencias y tecnolog\u00edas aprendiendo algo nuevo de cada una de nuestras construcciones y aportando m\u00e1s de nuestra experiencia a cada siguiente proyecto.<\/p>\n<p>Ofrecemos construcciones de piscinas en Tarragona por el m\u00e9todo de gunitado.<\/p>\n<p><span style=\"font-size: 19px;\"> En nuestras construcciones buscamos siempre la m\u00e1xima calidad y asesoramos siempre nuestros clientes para escoger los mejores materiales para que la estructura se mantenga intacta durante much\u00edsimos a\u00f1os.<\/span><\/p>\n<p>Si est\u00e1 interesado en <strong>construir su\u00a0piscina en la provincia Tarragona<\/strong>\u00a0no dude en contactar con nosotros a trav\u00e9s de nuestro <a href=\"https:\/\/www.julianpiscinas.com\/contacto-julian-i-olano-piscines\/\">formulario de contacto<\/a> o a trav\u00e9s de cualquiera de nuestros n\u00fameros de tel\u00e9fono.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb1400px\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; locked=\u00bboff\u00bb][et_pb_column _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_4&#8243;][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Cumplimiento de plazos<\/strong><\/h3>\n<p style=\"text-align: center;\"><span>Entendemos que una piscina es una inversi\u00f3n emocionante, y nos comprometemos a cumplir con los plazos acordados para que pueda disfrutar de su piscina en el menor tiempo posible.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_4&#8243;][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Calidad en los materiales y la construcci\u00f3n<\/strong><\/h3>\n<p style=\"text-align: center;\"><span>Utilizamos materiales de alta calidad y t\u00e9cnicas de construcci\u00f3n de vanguardia para garantizar la durabilidad y resistencia de su piscina. Nuestra atenci\u00f3n a los detalles asegura que el resultado sea s\u00f3lido y de bajo mantenimiento.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_4&#8243;][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Dise\u00f1o personalizado<\/strong><\/h3>\n<p style=\"text-align: center;\"><span>Nos enfocamos en escuchar sus ideas y necesidades para crear un dise\u00f1o de piscina que se adapte perfectamente a su espacio y estilo de vida. Nos aseguramos de que cada detalle sea cuidadosamente considerado para brindarle una piscina \u00fanica y funcional.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_4&#8243;][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Experiencia y conocimientos<\/strong><\/h3>\n<p style=\"text-align: center;\"><span>Contamos con un equipo de expertos en construcci\u00f3n de piscinas, con amplia experiencia en el dise\u00f1o y ejecuci\u00f3n de proyectos de este tipo. Nuestra trayectoria nos permite abordar diferentes estilos y tama\u00f1os de piscinas, asegurando un resultado final excepcional.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbConstrucci\u00f3n de piscinas en superficie en Tarragona\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/Construccion-de-piscinas-en-superficie-Tarragona.jpg\u00bb alt=\u00bbConstruccion de piscinas en superficie Tarragona\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Si prefiere construir piscinas sin hacer excavaciones, construimos su piscina de obra en superficie.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbMinipiscinas en Tarragona\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/construccion-de-piscinas-mini.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona minipiscinas\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Si dispone de poco espacio tambi\u00e9n puede disfrutar de una piscina. Realizamos minipiscinas de obra de calidad.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbCon zona de hidromasaje\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/pisicnas-con-arrea-de-hidromasaje.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona con hidromasaje\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Si quiere construir una piscina con hidromasaje en Tarragona o a\u00f1adir una zona de hidromasaje a su piscina contacte con nosotros.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbPara nataci\u00f3n\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/piscinas-para-natacion.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona para nataci\u00f3n\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Si desea una piscina para nataci\u00f3n y no dispone de mucho espacio recomendamos una piscina larga y estrecha. Construimos piscinas de nataci\u00f3n de cualquier dimensi\u00f3n.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbCuadradas\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/piscinas-cuadradas.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona cuadradas\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Construimos piscinas cuadradas para encajar en el dise\u00f1o de su propiedad.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbRectangulares\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/piscinas-rectangulares.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona rectangulares\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Las piscinas rectangulares son las m\u00e1s populares.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbRedondas\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/piscinas-redondas.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona redondas\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Las piscinas redondas dan siempre un toque de clase y encajan tanto en dise\u00f1os modernos como en dise\u00f1os org\u00e1nicos.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbPiscinas de grande superficie\u00bb image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/piscinas-de-grande-superficie.jpg\u00bb alt=\u00bbConstruccion de piscinas en superficie Tarragona\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#006AC1&#8243; body_text_align=\u00bbleft\u00bb body_font_size=\u00bb14px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Construimos piscinas de todos los tama\u00f1os. Contacta con nosotros y solicita presupuesto sin compromiso.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.17.4&#8243; width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.4&#8243; text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><strong>Construcciones de todo tipo de piscinas<\/strong><\/h3>\n<p>La construcci\u00f3n de piscinas es un proceso que puede variar en complejidad y duraci\u00f3n dependiendo del tipo de piscina que se est\u00e9 construyendo. Desde piscinas peque\u00f1as y sencillas hasta complejos acu\u00e1ticos de gran envergadura, la construcci\u00f3n de una piscina requiere de planificaci\u00f3n, dise\u00f1o y construcci\u00f3n profesional.<\/p>\n<p>El proceso general de construcci\u00f3n de una piscina comienza con la excavaci\u00f3n del \u00e1rea donde se ubicar\u00e1 la piscina. A continuaci\u00f3n, se construye una estructura de acero o concreto que servir\u00e1 como soporte y se instalan las tuber\u00edas y el sistema de filtraci\u00f3n. Luego, se coloca el revestimiento de la piscina, ya sea en forma de azulejos, vinilo o fibra de vidrio.<\/p>\n<p>El siguiente paso es llenar la piscina con agua y realizar pruebas para asegurarse de que todo el sistema de filtraci\u00f3n, bombas y tuber\u00edas funcionan correctamente. Una vez que se han realizado todas las pruebas y se ha asegurado la calidad del agua, la piscina est\u00e1 lista para ser disfrutada.<\/p>\n<p>Es importante destacar que la construcci\u00f3n de una piscina debe ser realizada por profesionales capacitados y experimentados, ya que cualquier error en el proceso de construcci\u00f3n puede tener consecuencias graves. Adem\u00e1s, la construcci\u00f3n de una piscina puede requerir permisos y cumplir con regulaciones espec\u00edficas en funci\u00f3n de la ubicaci\u00f3n de la piscina y el tipo de construcci\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2023\/02\/piscina.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona\u00bb title_text=\u00bbConstrucci\u00f3n de piscinas en Tarragona\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.16&#8243; width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.4&#8243; text_font=\u00bb|600||on|||||\u00bb text_text_color=\u00bb#ffffff\u00bb background_image=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2016\/04\/fra-134-e1459866684250.jpg\u00bb min_height=\u00bb350px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb38%||||false|false\u00bb text_text_shadow_style=\u00bbpreset5&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Especialistas en piscinas en Tarragona<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.4&#8243; text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Somos especialistas en construcci\u00f3n de piscinas en Tarragona<\/strong><\/h2>\n<p>Nos damos cuenta de que construir una piscina no es una decisi\u00f3n impulsiva. Es algo en lo que has estado pensando durante un tiempo, quiz\u00e1s a\u00f1os. \u00a1Ahora ha llegado el momento de hacer tu piscina realidad!<\/p>\n<p>Tienes que tomar muchas decisiones cuando decides construir tu piscina. \u00bfDe qu\u00e9 tama\u00f1o deber\u00eda ser, qu\u00e9 forma quieres, que presupuesto fijas? \u00bfQuieres hormig\u00f3n, fibra de vidrio o estructura de liner armado de PVC? Las opciones pueden ser abrumadoras. Tenemos buenas noticias para ti porque en Julian Piscines tenemos una piscina que se adapta a cualquier jard\u00edn, presupuesto y estilo de vida: tu piscina hecha a medida. Construimos piscinas en Tarragona asesor\u00e1ndote en todo el proceso para obtener el mejor equilibrio entre tus necesidades, deseos y presupuesto.<\/p>\n<p>Quiz\u00e1s este pensando: \u00ab\u00bfQu\u00e9 quiero yo de mi piscina, que quiero que me aporte este gasto?\u00bb \u00bfLa usare principalmente para ejercicio? \u00bfEntretenimiento? \u00bfUn lugar para relajarse y disfrutar con la familia? \u00bfO tal vez, solo tal vez es para decir \u00abPorque puedo!\u00bb?\u00a1Has trabajado duro y ahora es tiempo de disfrutar los frutos de tu trabajo!<\/p>\n<p>\u00a1Cualquiera sea la motivaci\u00f3n para tu nueva piscina en Tarragona, la tomaremos en consideraci\u00f3n en el dise\u00f1o de esta y la construimos tal como la necesitas!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbtel:+34600811678&#8243; button_text=\u00bbLl\u00e1manos\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIxMSJ9fQ==@\u00bb button_text=\u00bbContacta con nosotros\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Empresa de gunitado de piscinas en Tarragona<\/h2>\n<h3>Conoce m\u00e1s sobre nuestro proceso de construcci\u00f3n de piscinas<\/h3>\n<p>Conocida por su resistencia estructural confiable, la gunita es una mezcla hormigonera de arena, cemento y agua que se aplica a trav\u00e9s de una manguera de alta presi\u00f3n. Una vez que se cura (se seca), la gunita se vuelve dura como una roca, formando una estructura gruesa y s\u00f3lida. Durante d\u00e9cadas, ha ocupado un lugar especial en la construcci\u00f3n de piscinas, donde siempre se combina con otro material de construcci\u00f3n fuerte, como el acero, as\u00ed como una capa de yeso para acabado interior.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/08\/construccion-de-piscinas-en-Tarragona.jpg\u00bb alt=\u00bbConstrucci\u00f3n de piscinas en Tarragona estructura\u00bb title_text=\u00bbConstrucci\u00f3n de piscinas en Tarragona estructura\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb height=\u00bb20vw\u00bb height_tablet=\u00bb20vw\u00bb height_phone=\u00bb20vw\u00bb height_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Instalaci\u00f3n de la estructura de resistencia<\/h3>\n<p>En el caso de la estructura de resistencia de acero, despu\u00e9s de que se excava un agujero para una nueva piscina, instalamos una red de barras de acero. Estas son conocidas como barras de refuerzo. Las barras de refuerzo son cuidadosamente colocadas a intervalos espec\u00edficos para formar un marco en forma de jaula. Esta estructura se extiende a lo largo de todo el tramo de la futura piscina. El acero adicional entra en \u00e1reas que requieren niveles de refuerzo especialmente altos. Por ejemplo en un extremo profundo o una pared elevada independiente.<br \/>Ubicada sobre bloques de concreto, la jaula est\u00e1 suspendida varias pulgadas en el aire para que no toque el suelo debajo de ella. De esta manera, queda mucho espacio por llenar con material de gunitado fresco.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=xH746Heb9G4&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb height=\u00bb20vw\u00bb height_tablet=\u00bb20vw\u00bb height_phone=\u00bb20vw\u00bb height_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Construcci\u00f3n del vaso de hormig\u00f3n<\/h3>\n<div><span>El uso de hormig\u00f3n en la construcci\u00f3n de piscinas ofrece numerosas ventajas, como su capacidad para adaptarse a diferentes formas y tama\u00f1os, su resistencia al agua y su durabilidad a largo plazo.<\/span><\/div>\n<div><span><\/span><\/div>\n<div>Los equipos de presi\u00f3n roc\u00edan la mezcla de concreto a alta velocidad sobre el acero en toda la piscina, creando el denso piso y paredes de la piscina. El gunitado produce l\u00edneas fluidas, varios contornos, profundidades y formas, todo junto en una estructura cohesiva y visualmente atractiva.<\/div>\n<p>[\/et_pb_text][et_pb_wc_reviews _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_reviews][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2021\/06\/replasterizado-de-piscina.jpg\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb max_height=\u00bb18vw\u00bb max_height_tablet=\u00bb18vw\u00bb max_height_phone=\u00bb18vw\u00bb max_height_last_edited=\u00bbon|phone\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Impermeabilizaci\u00f3n del vaso<\/h3>\n<p>Despu\u00e9s de que la gunita se cura adecuadamente, se aplica un tercer material para completar una piscina de gunita: yeso. Compuesto de cemento y polvo de m\u00e1rmol, la mezcla suave tambi\u00e9n puede contener agregado de cuarzo coloreado para mayor durabilidad y est\u00e9tica. (Para algunas piscinas, se puede usar un yeso de guijarros de alta calidad). El yeso es lo que realmente impermeabiliza una piscina de gunita, y este recubrimiento final es lo que todos ven como la superficie interior reluciente de la piscina.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.julianpiscinas.com\/wp-content\/uploads\/2022\/08\/construccion-de-piscinas-tarragona-accesorios.jpg\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb max_height=\u00bb18vw\u00bb max_height_tablet=\u00bb18vw\u00bb max_height_phone=\u00bb18vw\u00bb max_height_last_edited=\u00bbon|tablet\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.4&#8243; header_2_font=\u00bb|||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#006AC1&#8243; text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Acabados y accesorios<\/h3>\n<p>Otros elementos cr\u00edticos entran en la construcci\u00f3n de una piscina de gunita. Entre ellos azulejos, plomer\u00eda, electricidad y revestimiento perimetral. Sin embargo, lo que diferencia a la construcci\u00f3n de gunita de otros tipos de piscinas es la gunita, el acero y el yeso. Es por ello, el uso de estos elementos, que el proyecto completado ofrece la incre\u00edble durabilidad y versatilidad de dise\u00f1o de piscinas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_post_slider posts_number=\u00bb3&#8243; include_categories=\u00bb6&#8243; show_arrows=\u00bboff\u00bb more_text=\u00bbVer entrada blog\u00bb use_manual_excerpt=\u00bboff\u00bb excerpt_length=\u00bb300&#8243; show_meta=\u00bboff\u00bb use_bg_overlay=\u00bboff\u00bb use_text_overlay=\u00bboff\u00bb dot_nav_custom_color=\u00bb#ffffff\u00bb module_class=\u00bbds-advent-8&#8243; _builder_version=\u00bb4.17.4&#8243; header_font=\u00bbRoboto|500||on|||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#0C71C3&#8243; header_font_size=\u00bb18&#8243; header_letter_spacing=\u00bb2px\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#232323&#8243; body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.5em\u00bb meta_text_align=\u00bbcenter\u00bb background_color=\u00bb#ffffff\u00bb background_color_gradient_direction=\u00bb90deg\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16&#8243; button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#232323&#8243; button_border_radius=\u00bb0&#8243; button_letter_spacing=\u00bb4&#8243; button_font=\u00bbRoboto Condensed|||on|||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb background_layout=\u00bblight\u00bb module_alignment=\u00bbleft\u00bb custom_padding=\u00bb|||\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb5000&#8243; custom_css_slide_description=\u00bbbackground-color:rgba(255,255,255,0.76);max-width:50%;float:right;max-height:80%;padding-top:2em;padding-bottom:3em;margin-top:10vh;margin-bottom:10vh;display:flex;flex-flow:column;justify-content:space-around;\u00bb button_text_color_hover=\u00bb#232323&#8243; button_border_radius_hover=\u00bb0&#8243; button_letter_spacing_hover=\u00bb4&#8243; button_bg_color_hover=\u00bbrgba(255,255,255,0)\u00bb show_inner_shadow=\u00bboff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#232323&#8243; button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bbon\u00bb button_border_radius__hover=\u00bb0&#8243; button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb4&#8243; button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bbrgba(255,255,255,0)\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb custom_css_slide_description_last_edited=\u00bbon|phone\u00bb custom_css_slide_description_tablet=\u00bbbackground-color:#ffffff80;max-width:80%;max-height:80%;padding-top:1em;\u00bb custom_css_slide_description_phone=\u00bbbackground-color:#ffffff80;max-width:90%;float:none;max-height:100%;padding-top:1em;margin-bottom:5em;margin-top:2em;\u00bb][\/et_pb_post_slider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbSecci\u00f3n\u00bb _builder_version=\u00bb4.17.4&#8243; background_color=\u00bb#006AC1&#8243; custom_padding=\u00bb27px|0px|0px|0px\u00bb custom_padding_tablet=\u00bb50px|0|50px|0&#8243; custom_padding_phone=\u00bb\u00bb transparent_background=\u00bboff\u00bb padding_mobile=\u00bboff\u00bb global_module=\u00bb468&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; padding_mobile=\u00bboff\u00bb column_padding_mobile=\u00bbon\u00bb _builder_version=\u00bb4.17.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb95%\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbUBICACI\u00d3N\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x52;||divi||400&#8243; icon_color=\u00bb#efef9e\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.17.4&#8243; header_text_color=\u00bb#FFFFFF\u00bb body_text_color=\u00bb#FFFFFF\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb background_layout=\u00bbdark\u00bb use_border_color=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Bloque Santo Tom\u00e1s. Esc. E 5\u00ba-1\u00aa<br \/>43007 &#8211; Sant Pau i Sant Pere (Tarragona)<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbCONTACTO\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x52;||divi||400&#8243; icon_color=\u00bb#efef9e\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.17.4&#8243; header_text_color=\u00bb#FFFFFF\u00bb body_text_color=\u00bb#FFFFFF\u00bb body_link_text_color=\u00bb#9bfffb\u00bb body_link_line_height=\u00bb2em\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb background_layout=\u00bbdark\u00bb use_border_color=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>M\u00f3vil: <strong><a href=\"tel:+34600811678\">600 811 678<\/a><\/strong><br \/>M\u00f3vil: <strong> <a href=\"tel:+34671581032\">671 581 032<\/a><\/strong><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbHORARIO\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x52;||divi||400&#8243; icon_color=\u00bb#efef9e\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.17.4&#8243; header_text_color=\u00bb#FFFFFF\u00bb body_text_color=\u00bb#FFFFFF\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb background_layout=\u00bbdark\u00bb use_border_color=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Lunes a Viernes :<br \/>09.00h a 13.30h<br \/>17.00h a 19.00h<br \/>S\u00e1bado :<br \/>09.00 a 13.30h<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbREDES SOCIALES\u00bb url=\u00bbhttps:\/\/goo.gl\/maps\/XPoazdzeDdy\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x52;||divi||400&#8243; icon_color=\u00bb#efef9e\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.17.4&#8243; header_text_color=\u00bb#FFFFFF\u00bb body_text_color=\u00bb#FFFFFF\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb background_layout=\u00bbdark\u00bb use_border_color=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_social_media_follow _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/profile.php?id=100057597542963&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#3b5998&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/julianpiscinas\/\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ea2c59&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbyoutube\u00bb url=\u00bbhttps:\/\/www.youtube.com\/channel\/UCvx5x4LoATHWd1GUWQM8fYA\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#a82400&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]youtube[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbgoogle\u00bb url=\u00bbhttps:\/\/goo.gl\/maps\/gq2kHcXktgK2&#8243; _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#4285f4&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]google[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bblinkedin\u00bb url=\u00bbhttps:\/\/www.linkedin.com\/in\/julian-piscinas-86a250173\/\u00bb _builder_version=\u00bb4.17.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#004472&#8243; background_enable_color=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Construcci\u00f3n de piscinas en Tarragona Piscinas de obra de todos los tama\u00f1os Empresa constructora experta en construcci\u00f3n de piscinas en la provincia Tarragona | Piscinas de gunitado | Piscinas de liner armado de PVC Construimos tu piscina al mejor precio en cualquier tama\u00f1oJulian Pisicinas Tarragona\u00a1Los dise\u00f1adores y constructores de Juli\u00e1n Piscinas llevamos tu piscina desde [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-705","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Construcci\u00f3n de piscinas en Tarragona - piscinas de obra hormig\u00f3n<\/title>\n<meta name=\"description\" content=\"Expertos en construcci\u00f3n de piscinas en Tarragona. Piscinas de obra de calidad en toda la provincia. Durabilidad y acabados excelentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.julianpiscinas.com\/ca\/construccion-de-piscinas-en-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Construcci\u00f3n de piscinas en Tarragona - piscinas de obra hormig\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Expertos en construcci\u00f3n de piscinas en Tarragona. Piscinas de obra de calidad en toda la provincia. Durabilidad y acabados excelentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.julianpiscinas.com\/ca\/construccion-de-piscinas-en-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"Jul\u00ed\u00e1n Piscines | construcci\u00f3n de piscinas | mantenimiento y reformas de piscinas | art\u00edculos y materiales de piscina\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-19T11:35:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.julianpiscinas.com\\\/construccion-de-piscinas-en-tarragona\\\/\",\"url\":\"https:\\\/\\\/www.julianpiscinas.com\\\/construccion-de-piscinas-en-tarragona\\\/\",\"name\":\"Construcci\u00f3n de piscinas en Tarragona - piscinas de obra hormig\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.julianpiscinas.com\\\/#website\"},\"datePublished\":\"2017-02-17T10:45:37+00:00\",\"dateModified\":\"2023-07-19T11:35:42+00:00\",\"description\":\"Expertos en construcci\u00f3n de piscinas en Tarragona. Piscinas de obra de calidad en toda la provincia. Durabilidad y acabados excelentes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.julianpiscinas.com\\\/construccion-de-piscinas-en-tarragona\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.julianpiscinas.com\\\/construccion-de-piscinas-en-tarragona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.julianpiscinas.com\\\/construccion-de-piscinas-en-tarragona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.julianpiscinas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construcci\u00f3n de piscinas en Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.julianpiscinas.com\\\/#website\",\"url\":\"https:\\\/\\\/www.julianpiscinas.com\\\/\",\"name\":\"Jul\u00ed\u00e1n Piscines | construcci\u00f3n de piscinas | mantenimiento y reformas de piscinas | art\u00edculos y materiales de piscina\",\"description\":\"Construcci\u00f3n y instalaci\u00f3n de piscinas en Els Pallaresos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.julianpiscinas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Construcci\u00f3n de piscinas en Tarragona - piscinas de obra hormig\u00f3n","description":"Expertos en construcci\u00f3n de piscinas en Tarragona. Piscinas de obra de calidad en toda la provincia. Durabilidad y acabados excelentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.julianpiscinas.com\/ca\/construccion-de-piscinas-en-tarragona\/","og_locale":"ca_ES","og_type":"article","og_title":"Construcci\u00f3n de piscinas en Tarragona - piscinas de obra hormig\u00f3n","og_description":"Expertos en construcci\u00f3n de piscinas en Tarragona. Piscinas de obra de calidad en toda la provincia. Durabilidad y acabados excelentes.","og_url":"https:\/\/www.julianpiscinas.com\/ca\/construccion-de-piscinas-en-tarragona\/","og_site_name":"Jul\u00ed\u00e1n Piscines | construcci\u00f3n de piscinas | mantenimiento y reformas de piscinas | art\u00edculos y materiales de piscina","article_modified_time":"2023-07-19T11:35:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"8 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.julianpiscinas.com\/construccion-de-piscinas-en-tarragona\/","url":"https:\/\/www.julianpiscinas.com\/construccion-de-piscinas-en-tarragona\/","name":"Construcci\u00f3n de piscinas en Tarragona - piscinas de obra hormig\u00f3n","isPartOf":{"@id":"https:\/\/www.julianpiscinas.com\/#website"},"datePublished":"2017-02-17T10:45:37+00:00","dateModified":"2023-07-19T11:35:42+00:00","description":"Expertos en construcci\u00f3n de piscinas en Tarragona. Piscinas de obra de calidad en toda la provincia. Durabilidad y acabados excelentes.","breadcrumb":{"@id":"https:\/\/www.julianpiscinas.com\/construccion-de-piscinas-en-tarragona\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.julianpiscinas.com\/construccion-de-piscinas-en-tarragona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.julianpiscinas.com\/construccion-de-piscinas-en-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.julianpiscinas.com\/"},{"@type":"ListItem","position":2,"name":"Construcci\u00f3n de piscinas en Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/www.julianpiscinas.com\/#website","url":"https:\/\/www.julianpiscinas.com\/","name":"Jul\u00ed\u00e1n Piscines | construcci\u00f3n de piscinas | mantenimiento y reformas de piscinas | art\u00edculos y materiales de piscina","description":"Construcci\u00f3n y instalaci\u00f3n de piscinas en Els Pallaresos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.julianpiscinas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/pages\/705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/comments?post=705"}],"version-history":[{"count":45,"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/pages\/705\/revisions"}],"predecessor-version":[{"id":2182,"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/pages\/705\/revisions\/2182"}],"wp:attachment":[{"href":"http:\/\/www.julianpiscinas.com\/ca\/wp-json\/wp\/v2\/media?parent=705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}